{"id":686,"date":"2019-02-05T09:21:55","date_gmt":"2019-02-05T09:21:55","guid":{"rendered":"https:\/\/rallycheck.com\/?p=686"},"modified":"2020-02-14T14:14:41","modified_gmt":"2020-02-14T13:14:41","slug":"bunnik-try-out","status":"publish","type":"post","link":"https:\/\/rallycheck.com\/nl\/bunnik-try-out\/","title":{"rendered":"Bunnik Toutklasse"},"content":{"rendered":"<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><div style='padding-bottom:10px; ' class='av-special-heading av-special-heading-h3    '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Bunnik Tourklasse<\/h3><div class='special-heading-border'><div class='special-heading-inner-border' ><\/div><\/div><\/div><\/div>\n<div class=\"flex_column av_one_half  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><p><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>Een korte route in het midden van het land om de Rallycheck app te testen.<\/p>\n<\/div><\/section><br \/>\n<div class='avia-icon-list-container  '><ul class='avia-icon-list avia-icon-list-left av-iconlist-big avia_animate_when_almost_visible avia-iconlist-animate'>\n<li><div  class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue842' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\"  >Startlocatie<\/h4><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><p>Postillion Hotel Bunnik<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue840' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\"  >Niveau<\/h4><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><p>Tourklasse<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue843' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\"  >Afstand<\/h4><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><p>19 Kilometer<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue862' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\"  >Tijdsduur route<\/h4><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><p>ca. 38 minuten<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue841' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\"  >Systeem<\/h4><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><p>Pijlen kortste route<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<li><div  class='iconlist_icon  avia-font-entypo-fontello'><span class='iconlist-char ' aria-hidden='true' data-av_icon='\ue80a' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='iconlist_content_wrap'><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\"  >Uitzetter<\/h4><\/header><div class='iconlist_content  '  itemprop=\"text\"  ><p>Joep Wanders<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class='iconlist-timeline'><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n<div class=\"flex_column av_one_half  flex_column_div av-zero-column-padding   \" style='border-radius:0px; '><p><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>Als je de Rallycheck app op je telefoon hebt ge\u00efnstalleerd, kan je het routeboek van deze rally opvragen. Met het geprinte routeboek en de Rallycheck app kan je vervolgens de rally rijden.<\/p>\n<p>Onderstaand een (vervaagd) voorbeeld van de routekaart in het routeboek. Het routeboek bevat alle informatie om de route te rijden.<\/p>\n<\/div><\/section><br \/>\n<div class='avia-image-container  av-styling-    avia-align-center '  itemprop=\"ImageObject\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img class='avia_image' src='https:\/\/rallycheck.com\/wp-content\/uploads\/2019\/02\/Try-out-Rally-App-Bunnik-route.png' alt='' title='Try-out Rally App Bunnik - route' height=\"706\" width=\"1015\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/p><\/div>\n<form action=\"https:\/\/rallycheck.com\/nl\/bunnik-try-out\/\" method=\"post\"  class=\"avia_ajax_form av-form-labels-visible    \" data-avia-form-id=\"1\" data-avia-redirect=''><fieldset><h3>Ik wil deze rally rijden<\/h3><p class=' first_form  form_element form_fullwidth' id='element_avia_1_1'><label for=\"avia_1_1\">Mijn e-mail adres <abbr class=\"required\" title=\"required\">*<\/abbr><\/label> <input name=\"avia_1_1\" class=\"text_input is_email\" type=\"text\" id=\"avia_1_1\" value=\"\" \/><\/p><p class=' first_form  form_element form_fullwidth' id='element_avia_2_1'><label for=\"avia_2_1\">Voornaam: <abbr class=\"required\" title=\"required\">*<\/abbr><\/label> <input name=\"avia_2_1\" class=\"text_input is_empty\" type=\"text\" id=\"avia_2_1\" value=\"\" \/><\/p><p class=' first_form  form_element form_fullwidth' id='element_avia_3_1'><label for=\"avia_3_1\">Tussenvoegsel:<\/label> <input name=\"avia_3_1\" class=\"text_input \" type=\"text\" id=\"avia_3_1\" value=\"\" \/><\/p><p class=' first_form  form_element form_fullwidth' id='element_avia_4_1'><label for=\"avia_4_1\">Achternaam: <abbr class=\"required\" title=\"required\">*<\/abbr><\/label> <input name=\"avia_4_1\" class=\"text_input is_empty\" type=\"text\" id=\"avia_4_1\" value=\"\" \/><\/p><p class=\"hidden\"><input type=\"text\" name=\"avia_5_1\" class=\"hidden \" id=\"avia_5_1\" value=\"\" \/><\/p><p class='' id='element_avia_6_1'>    <span class='value_verifier_label'>1 + 1 = ?<\/span>    <input name=\"avia_6_1_verifier\" type=\"hidden\" id=\"avia_6_1_verifier\" value=\"622274173\"\/><label for=\"avia_6_1\">Bewijs a.u.b. dat u een mens bent door de volgende vergelijking op te lossen. <abbr class=\"required\" title=\"required\">*<\/abbr><\/label>    <input name=\"avia_6_1\" class=\"text_input captcha\" type=\"text\" id=\"avia_6_1\" value=\"\"\/><\/p><p class=\"form_element \"><input type=\"hidden\" value=\"1\" name=\"avia_generated_form1\" \/><input type=\"submit\" value=\"Stuur mij het routeboek Bunnik Try-out\" class=\"button\"  data-sending-label=\"Verzenden\"\/><\/p><\/fieldset><\/form><div id=\"ajaxresponse_1\" class=\"ajaxresponse ajaxresponse_1 hidden\"><\/div>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><div class=\"av_gmaps_sc_main_wrap av_gmaps_main_wrap\"><div id='av_gmap_0' class='avia-google-map-container avia-google-map-sc av_gmaps_show_unconditionally av-no-fallback-img ' data-mapid='av_gmap_0'  style='height: 400px;'><a class=\"av_gmaps_browser_disabled av_text_confirm_link av_text_confirm_link_visible\" href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=Baan%20van%20Fectio%20%20Bunnik%20%20Nederland\" target=\"_blank\">Maps were disabled by the visitor on this site.<\/a><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":689,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-routeboek"],"jetpack_featured_media_url":"https:\/\/rallycheck.com\/wp-content\/uploads\/2019\/02\/Try-out-Rally-App-Bunnik-route.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/posts\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":15,"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"predecessor-version":[{"id":2710,"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/posts\/686\/revisions\/2710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/media\/689"}],"wp:attachment":[{"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rallycheck.com\/nl\/wp-json\/wp\/v2\/tags?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}